{"id":8624,"date":"2022-11-22T17:59:56","date_gmt":"2022-11-22T16:59:56","guid":{"rendered":"https:\/\/www.carmeleespanolonline.com\/blog\/?p=8624"},"modified":"2022-11-23T11:48:10","modified_gmt":"2022-11-23T10:48:10","slug":"como-pasar-la-prueba-oral-dele","status":"publish","type":"post","link":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/","title":{"rendered":"C\u00f3mo pasar  la prueba oral DELE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8624\" class=\"elementor elementor-8624\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54fa1dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54fa1dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d20917b\" data-id=\"d20917b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d41998 elementor-widget elementor-widget-text-editor\" data-id=\"7d41998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>\u00bfTe presentas al DELE?<\/strong><\/p><p style=\"text-align: center;\"><strong>\u00bfSabes c\u00f3mo pasar la prueba oral del DELE?<\/strong><\/p><p style=\"text-align: center;\"><strong>\u00bfQu\u00e9 tienes que tener en cuenta para conseguir un APTO?<\/strong><\/p><p>Si quieres conseguir tu APTO en las tareas orales del examen DELE del Instituto Cervantes, \u00a1tienes que leer este art\u00edculo!<\/p><p style=\"text-align: center;\"><em>Te voy a contar qu\u00e9 es lo que tenemos en cuenta los examinadores de DELE para dar un APTO o NO APTO a las prueba orales de los candidatos.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5eefd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5eefd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87d7ac9\" data-id=\"87d7ac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65a81a2 elementor-widget elementor-widget-heading\" data-id=\"65a81a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/carmeleespanolonline.com\/blog\/como-hacer-el-examen-dele\/\" target=\"_blank\">Para saber c\u00f3mo pasar las pruebas escritas pincha aqu\u00ed<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-943d226 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"943d226\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0460395\" data-id=\"0460395\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fb41df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fb41df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c44d0f0\" data-id=\"c44d0f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d013b2f elementor-widget elementor-widget-text-editor\" data-id=\"d013b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el art\u00edculo anterior, te hablo de forma general de la correcci\u00f3n de los ex\u00e1menes DELE.<\/p><p>Si quieres sabes c\u00f3mo es la correcci\u00f3n de las pruebas de Comprensi\u00f3n lectora, auditiva o de las tareas de Expresi\u00f3n e Interacci\u00f3n escritas puedes leerlo detenidamente.<\/p><p style=\"text-align: center;\"><strong>En este art\u00edculo nos vamos a centrar en la prueba de Expresi\u00f3n e Interacci\u00f3n oral.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3323e55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3323e55\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-949858c\" data-id=\"949858c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76b1cf9 elementor-widget elementor-widget-text-editor\" data-id=\"76b1cf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #1e73be;color:#1e73be\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #1e73be;color:#1e73be\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#Como_pasar_la_prueba_oral_DELE\" >C\u00f3mo pasar la prueba oral DELE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#La_prueba_de_Expresion_e_Interaccion_oral_esta_compuesta_por_varias_tareas_algunas_puedes_prepararlas_un_poco_antes_en_la_sala_de_preparacion_y_otras_no_%C2%BFSabes_como_prepararlas_para_tener_un_APTO_%C2%BFQue_aspectos_debes_tener_en_cuenta\" >La prueba de Expresi\u00f3n e Interacci\u00f3n oral, est\u00e1 compuesta por varias tareas, algunas puedes prepararlas un poco antes en la sala de preparaci\u00f3n \u00a0y otras no. \u00bfSabes c\u00f3mo prepararlas para tener un APTO? \u00bfQu\u00e9 aspectos debes tener en cuenta?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#Como_pasar_la_prueba_oral_DELE_A1-A2\" >C\u00f3mo pasar la prueba oral DELE A1-A2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#Como_pasar_las_pruebas_orales_de_los_examenes_B1_B2_y_C\" >C\u00f3mo pasar las pruebas orales de los ex\u00e1menes B1, B2 y C<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#Consejos_generales_para_pasar_el_examen_oral_DELE\" >Consejos generales para pasar el examen oral DELE<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Como_pasar_la_prueba_oral_DELE\"><\/span><span style=\"color: #1569ae;\"><strong>C\u00f3mo pasar la prueba oral DELE<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2><h2><span class=\"ez-toc-section\" id=\"La_prueba_de_Expresion_e_Interaccion_oral_esta_compuesta_por_varias_tareas_algunas_puedes_prepararlas_un_poco_antes_en_la_sala_de_preparacion_y_otras_no_%C2%BFSabes_como_prepararlas_para_tener_un_APTO_%C2%BFQue_aspectos_debes_tener_en_cuenta\"><\/span><span style=\"font-family: Lato, sans-serif; font-size: 16px; color: var( --e-global-color-text ); letter-spacing: var( --e-global-typography-text-letter-spacing );\">La prueba de Expresi\u00f3n e Interacci\u00f3n oral, est\u00e1 compuesta <\/span><strong style=\"font-family: Lato, sans-serif; font-size: 16px; color: var( --e-global-color-text ); letter-spacing: var( --e-global-typography-text-letter-spacing );\">por varias tareas,<\/strong><span style=\"font-family: Lato, sans-serif; font-size: 16px; color: var( --e-global-color-text ); letter-spacing: var( --e-global-typography-text-letter-spacing );\"> algunas puedes prepararlas un poco antes en la sala de preparaci\u00f3n \u00a0y otras no. <\/span><strong style=\"font-family: Lato, sans-serif; font-size: 16px; color: var( --e-global-color-text ); letter-spacing: var( --e-global-typography-text-letter-spacing );\">\u00bfSabes c\u00f3mo prepararlas para tener un APTO? \u00bfQu\u00e9 aspectos debes tener en cuenta?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><p>Antes de comentarte c\u00f3mo puedes hacer tu prueba para conseguir el APTO, te voy a hablar sobre <strong>la sala de examen<\/strong> y las personas que est\u00e1n en ella. Cuando entras en la sala ver\u00e1s a <strong>dos personas, un calificador y un examinador.<\/strong> Hablar\u00e1s con el examinador y el calificador estar\u00e1 detr\u00e1s de ti escuchando tu prueba.<\/p><p style=\"text-align: center;\"><strong>Ambos van a evaluarte<\/strong>.<\/p><p>Como en la prueba de Expresi\u00f3n e Interacci\u00f3n escrita, aqu\u00ed tambi\u00e9n hay una <strong>doble evaluaci\u00f3n<\/strong>. Esto es bueno para ti, porque as\u00ed se <strong>garantiza la objetividad de la evaluaci\u00f3n.<\/strong><\/p><p>El calificador hace una correcci\u00f3n m\u00e1s detallada y el examinador general, igual que en las tareas escritas. Las llamamos <strong>correcci\u00f3n Anal\u00edtica y Hol\u00edstica.<\/strong> Estas correcciones tienen unos puntos,<strong> descriptores<\/strong> con unos niveles valorados entre 0-3, ambas personas deben de ponerte un n\u00famero en funci\u00f3n de estos criterios y de ah\u00ed saldr\u00e1 tu valoraci\u00f3n. <em>Si est\u00e1s entre el 0-1 ser\u00e1s NO APTO, si est\u00e1s entre 2-3 ser\u00e1s APTO en esta prueba.<\/em><\/p><p>Digamos que los dos examinadores deben ponerse de acuerdo, siguiendo los descriptores.<\/p><p>Para saber c\u00f3mo pasar la prueba oral del examen DELE, lo mejor es tener en cuenta los descriptores que vamos a usar los examinadores. \u00a1As\u00ed que adelante!<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72551cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72551cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-155fe2d\" data-id=\"155fe2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58d2961 elementor-widget elementor-widget-text-editor\" data-id=\"58d2961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote><p>En mis clases de preparaci\u00f3n al DELE nos centramos en los niveles 2 y 3 \u00a1que es d\u00f3nde queremos estar!<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6599d28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6599d28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fb24ba\" data-id=\"3fb24ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a643ae3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a643ae3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-416ad87\" data-id=\"416ad87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f51aa7 elementor-widget elementor-widget-text-editor\" data-id=\"8f51aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Como_pasar_la_prueba_oral_DELE_A1-A2\"><\/span><strong><span style=\"color: #1569ae;\">C\u00f3mo pasar la prueba oral DELE A1-A2<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3><p><strong>La prueba oral<\/strong> del examen <strong>DELE A1 y A2 consta de tres tareas,<\/strong> tienes tiempo para preparar las tareas 1 y 2 pero la tarea 3 ser\u00e1 un di\u00e1logo con el examinador. Todas las tareas est\u00e1n <strong>adaptadas a\u00a0 tu nivel<\/strong>, as\u00ed que tranquilo\/a porque si est\u00e1s preparado correctamente no ser\u00e1n un problema. Pero <em>es importante que sepas que van a valorar en cada una de ellas.<\/em><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2712e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2712e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe80125\" data-id=\"fe80125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-becac51 elementor-widget elementor-widget-heading\" data-id=\"becac51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/carmeleespanolonline.com\/blog\/examen-dele-a1-y-a2\/\" target=\"_blank\">Pincha aqu\u00ed si quieres saber c\u00f3mo son los ex\u00e1menes A1 y A2<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bc75b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bc75b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c2de68\" data-id=\"3c2de68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4799ba3 elementor-widget elementor-widget-text-editor\" data-id=\"4799ba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como en la prueba de expresi\u00f3n e intracci\u00f3n escrita, nos centramos en el<strong> Uso de la lengua y el cumplimiento de la lengua<\/strong>. Es decir, c\u00f3mo utilizas los tiempos verbales, per\u00edfrasis, c\u00f3mo es tu pronunciaci\u00f3n, la formaci\u00f3n de oraciones y claridad de tu discurso y si hablas con detalle o no de todos los puntos que se piden en cada tarea.<\/p><p>Te dejo aqu\u00ed <strong>los descriptores\u00a0 de las tareas<\/strong> (recuerda que solo te ense\u00f1o los descriptores considerados APTOS)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f13b75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f13b75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8595c9\" data-id=\"b8595c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4665e64 elementor-widget elementor-widget-image\" data-id=\"4665e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2-1024x768.png\" class=\"attachment-large size-large wp-image-8699\" alt=\"Descriptores prueba oral A2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2-1024x768.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2-300x225.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2-768x576.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2-600x450.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-A1A2.png 1106w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptores prueba oral DELE A2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-346f4ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"346f4ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d28be38\" data-id=\"d28be38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe8232b elementor-widget elementor-widget-image\" data-id=\"fe8232b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"597\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2-1024x597.png\" class=\"attachment-large size-large wp-image-8700\" alt=\"Descriptores prueba oral A2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2-1024x597.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2-300x175.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2-768x448.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2-600x350.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-oral-a2.png 1104w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptores prueba oral A2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abec2c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abec2c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88ca972\" data-id=\"88ca972\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3761fa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3761fa0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6d0552\" data-id=\"b6d0552\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c20043 elementor-widget elementor-widget-text-editor\" data-id=\"2c20043\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"Como_pasar_las_pruebas_orales_de_los_examenes_B1_B2_y_C\"><\/span><strong><span style=\"color: #1569ae;\">C\u00f3mo pasar las pruebas orales de los ex\u00e1menes B1, B2 y C<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3><p style=\"text-align: left;\">En las pruebas orales a partir del del B1 vamos a valorar los mismos descriptores, hablaremos de <strong>coherencia, fluidez, correcci\u00f3n y alcance<\/strong>. Primero hablaremos sobre\u00a0 <strong>qu\u00e9 se valora en cada uno de ellos<\/strong> y despu\u00e9s veremos\u00a0 de <strong>las diferencias\u00a0 entre niveles.<\/strong><\/p><blockquote><p>Recuerda que nos estamos centrando en la evaluaci\u00f3n anal\u00edtica, ya que nos da m\u00e1s informaci\u00f3n para preparar el examen.<\/p><\/blockquote><ul><li><strong>Coherencia:<\/strong> Se eval\u00faa c\u00f3mo elaboras tu discurso, s\u00ed es claro y adecuado al tema que se te ha pedido en las instrucciones, c\u00f3mo usas los conectores y por supuesto en c\u00f3mo mantienes la conversaci\u00f3n con el entrevistador.<\/li><li><strong>Fluidez:<\/strong> Se eval\u00faa tu facilidad de expresarte en espa\u00f1ol. C\u00f3mo hablas, tus pausas, si desarrollas las tareas con eficacia y tambi\u00e9n tu pronunciaci\u00f3n.<\/li><li><strong>Correcci\u00f3n:<\/strong> Aqu\u00ed se eval\u00faa tu control sobre las reglas gramaticales. Esto no quiere decir que no puedas tener errores, no, incluso si los tienes y te corriges es considerado algo bueno. Si no el control de estructuras y c\u00f3mo las usas.<\/li><li><strong>Alcance:<\/strong> Se eval\u00faa tu capacidad de expresarte y solucionar las tareas, el lenguaje que usas y las expresiones idiom\u00e1ticas. Ten en cuenta que debes usarlas en el contexto adecuado, si no las conoces bien mejor no usarlas.<\/li><\/ul><p>A continuaci\u00f3n te dejo los descriptores aptos de los diferentes niveles.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42d5705 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42d5705\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f81b6e5\" data-id=\"f81b6e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34545ee elementor-widget elementor-widget-heading\" data-id=\"34545ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">DESCRIPTORES NIVEL B1<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2990616 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2990616\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37cd8d3\" data-id=\"37cd8d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b51018 elementor-widget elementor-widget-image\" data-id=\"4b51018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"279\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-1024x279.png\" class=\"attachment-large size-large wp-image-8804\" alt=\"Descriptores orales DELE B1\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-1024x279.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-300x82.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-768x210.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-1536x419.png 1536w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1-600x164.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Descriptores-orales-B1.png 1554w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptores orales DELE B1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70f73aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70f73aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0798824\" data-id=\"0798824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8d30c1 elementor-widget elementor-widget-heading\" data-id=\"d8d30c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">DESCRIPTORES NIVEL B2<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e404577 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e404577\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5319f2\" data-id=\"f5319f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfff3c9 elementor-widget elementor-widget-image\" data-id=\"dfff3c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"414\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-B2.png\" class=\"attachment-large size-large wp-image-8805\" alt=\"Descritores orales B2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-B2.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-B2-300x121.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-B2-768x311.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-B2-600x243.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Coherencia DELE B2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-420a14f\" data-id=\"420a14f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac16841 elementor-widget elementor-widget-image\" data-id=\"ac16841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"414\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2-1024x414.png\" class=\"attachment-large size-large wp-image-8806\" alt=\"Descriptores oral DELE B2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2-1024x414.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2-300x121.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2-768x310.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2-600x243.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-B2.png 1034w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Fluidez oral DELE B2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22cdf88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22cdf88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cce0fd\" data-id=\"2cce0fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac5326 elementor-widget elementor-widget-image\" data-id=\"5ac5326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2-1024x300.png\" class=\"attachment-large size-large wp-image-8807\" alt=\"Descritor oral DELE B2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2-1024x300.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2-300x88.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2-768x225.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2-600x176.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-B2.png 1030w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Correcci\u00f3n oral DELE B2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7baf91d\" data-id=\"7baf91d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-836976a elementor-widget elementor-widget-image\" data-id=\"836976a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"370\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2-1024x370.png\" class=\"attachment-large size-large wp-image-8808\" alt=\"Descriptor oral DELE B2\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2-1024x370.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2-300x109.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2-768x278.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2-600x217.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-B2.png 1034w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Alcance oral DELE B2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18d92bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18d92bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ac9726\" data-id=\"9ac9726\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b26cfc0 elementor-widget elementor-widget-heading\" data-id=\"b26cfc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">DESCRIPTORES NIVEL C1<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d97435f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d97435f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-011c685\" data-id=\"011c685\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa32470 elementor-widget elementor-widget-image\" data-id=\"aa32470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1004\" height=\"412\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-C1.png\" class=\"attachment-large size-large wp-image-8812\" alt=\"Descriptores oral DELE C1\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-C1.png 1004w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-C1-300x123.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-C1-768x315.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Coherencia-oral-C1-600x246.png 600w\" sizes=\"(max-width: 1004px) 100vw, 1004px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Coherencia oral DELE C1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e44c4a6\" data-id=\"e44c4a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd2c6b4 elementor-widget elementor-widget-image\" data-id=\"cd2c6b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"342\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-C1.png\" class=\"attachment-large size-large wp-image-8813\" alt=\"Descriptor oral DELE C1\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-C1.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-C1-300x100.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-C1-768x257.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Fluidez-oral-C1-600x200.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Fluidez oral DELE C1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abac463 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abac463\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-125a345\" data-id=\"125a345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40475d5 elementor-widget elementor-widget-image\" data-id=\"40475d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"252\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1-1024x252.png\" class=\"attachment-large size-large wp-image-8814\" alt=\"Descriptor oral DELE C1\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1-1024x252.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1-300x74.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1-768x189.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1-600x148.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Correccion-oral-C1.png 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Correcci\u00f3n oral DELE C1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15c33ab\" data-id=\"15c33ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9a0652 elementor-widget elementor-widget-image\" data-id=\"a9a0652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1-1024x341.png\" class=\"attachment-large size-large wp-image-8815\" alt=\"Descriptor oral DELE C1\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1-1024x341.png 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1-300x100.png 300w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1-768x256.png 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1-600x200.png 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Alcance-oral-C1.png 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Descriptor de Alcance oral DELE C1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76b1c33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76b1c33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-381be22\" data-id=\"381be22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76b6e16 elementor-widget elementor-widget-heading\" data-id=\"76b6e16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Pincha aqu\u00ed si quieres saber m\u00e1s sobre el DELE B1<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2a9613 elementor-widget elementor-widget-heading\" data-id=\"e2a9613\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Pincha aqu\u00ed si quieres saber m\u00e1s sobre el DELE B2<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b93f59 elementor-widget elementor-widget-heading\" data-id=\"1b93f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Pincha aqu\u00ed si quieres saber m\u00e1s sobre el DELE C1<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8708de3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8708de3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b51d86d\" data-id=\"b51d86d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-925e4b7 elementor-widget elementor-widget-text-editor\" data-id=\"925e4b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"ez-toc-section\" id=\"Consejos_generales_para_pasar_el_examen_oral_DELE\"><\/span><strong><span style=\"color: #1569ae;\">Consejos generales para pasar el examen oral DELE<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><ul><li><strong>Demuestra lo que sabes:<\/strong> En el \u00a0examen DELE debes de demostrar todo lo que has estudiado. En tus intervenciones intenta incluir estructuras que ya has visto en clase, frases idiom\u00e1ticas y vocabulario adecuado a tu nivel.<\/li><li><strong>No te limites a frases cortas:<\/strong> Es importante que empieces a justificar tus respuestas, no te limites a frases sencillas y cortas.<\/li><li><strong>Ordena tu discurso:<\/strong> Igual que en las tareas de expresi\u00f3n escrita, aqu\u00ed tambi\u00e9n tienes que incluir conectores que den cuerpo y sentido a tu discurso. Es cierto que no es f\u00e1cil por eso te aconsejo que practiques mucho.<\/li><li><strong>Lee atentamente lo que se te pide:<\/strong> Es normal que con los nervios se te pase algo, intenta leer o preguntar aquello que no entiendas bien. Un error en este sentido puede llevar a la conclusi\u00f3n a tu examinador que no comprendes bien el idioma.\u00a0<\/li><li><strong>\u00a1Habla!:<\/strong> Es un examen oral, debes hablar, si te quedas bloqueado, continua con el siguiente punto, si no te sale una palabra la explicas con otras palabras\u2026 pero no te quedes callado por mucho tiempo en un examen.\u00a0<\/li><\/ul><p style=\"text-align: center;\"><strong>Recuerda que debes demostrar tu control y que podr\u00edas salir al pasado de las situaciones que te plantean en el examen.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60b9452 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60b9452\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7ae8f5\" data-id=\"a7ae8f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7a1746 elementor-widget elementor-widget-image\" data-id=\"b7a1746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-683x1024.jpg\" class=\"attachment-large size-large wp-image-2092\" alt=\"spanish teacher\" srcset=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-683x1024.jpg 683w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-scaled-600x900.jpg 600w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-200x300.jpg 200w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-768x1152.jpg 768w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-1024x1536.jpg 1024w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-1365x2048.jpg 1365w, https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2020\/09\/carmele-espanol-online-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c85408a\" data-id=\"c85408a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5db11c3 elementor-widget elementor-widget-text-editor\" data-id=\"5db11c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Si necesitas ayuda con tu preparaci\u00f3n al examen DELE, puedes ponerte en contacto conmigo.\u00a0<\/p><p>\u00a0<\/p><p style=\"text-align: center;\"><a href=\"https:\/\/carmeleespanolonline.com\/blog\/contacto\/\" target=\"_blank\" rel=\"noopener\">\u00a1Pide una cita y nos vemos!<\/a><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc3c17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bc3c17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfefe52\" data-id=\"cfefe52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddb544e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddb544e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a018398\" data-id=\"a018398\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1224710 elementor-widget elementor-widget-heading\" data-id=\"1224710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/youtube.com\/playlist?list=PLmyGhJmy-Z3tR_ZB7QPxaiCBAyK0A2OZT\" target=\"_blank\">Escucha DELEANDO POR EL MUNDO para saber m\u00e1s sobre los ex\u00e1menes DELE <\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conoce los aspectos importantes que tenemos en cuenta los examinadores para evaluar tu prueba oral de espa\u00f1ol en los ex\u00e1menes DELE. <\/p>\n","protected":false},"author":1,"featured_media":8824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[],"class_list":["post-8624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dele-y-siele"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Carmen de la Vega\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Online Spanish school for foreigners | Learn Spanish at home\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online\" \/>\n\t\t<meta property=\"og:description\" content=\"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-22T16:59:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-11-23T10:48:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#article\",\"name\":\"C\\u00f3mo pasar la prueba oral DELE | CarmEle Espa\\u00f1ol Online\",\"headline\":\"C\\u00f3mo pasar  la prueba oral DELE\",\"author\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/author\\\/carmen-de-la-vega\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Como-pasar-la-prueba-oral-DELE.png\",\"width\":442,\"height\":250,\"caption\":\"C\\u00f3mo pasar la prueba oral del DELE\"},\"datePublished\":\"2022-11-22T17:59:56+01:00\",\"dateModified\":\"2022-11-23T11:48:10+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#webpage\"},\"articleSection\":\"DELE, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/dele-y-siele\\\/#listItem\",\"name\":\"DELE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/dele-y-siele\\\/#listItem\",\"position\":2,\"name\":\"DELE\",\"item\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/dele-y-siele\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#listItem\",\"name\":\"C\\u00f3mo pasar  la prueba oral DELE\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo pasar  la prueba oral DELE\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/dele-y-siele\\\/#listItem\",\"name\":\"DELE\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#organization\",\"name\":\"Carmele Espa\\u00f1ol Online\",\"description\":\"Learn Spanish at home\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.carmeleespanolonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/cropped-Dise\\u00f1o-sin-t\\u00edtulo.jpg\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/author\\\/carmen-de-la-vega\\\/#author\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/author\\\/carmen-de-la-vega\\\/\",\"name\":\"Carmen de la Vega\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6834562093b67f5a64864fb30d6e6039390c3840f330a8e4d3ca9eb33d79152c?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"Carmen de la Vega\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#webpage\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/\",\"name\":\"C\\u00f3mo pasar la prueba oral DELE | CarmEle Espa\\u00f1ol Online\",\"description\":\"Conoce en qu\\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\\u00e1menes del Instituto Cervantes de espa\\u00f1ol. \\u00a1Consigue tu APTO en el DELE\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/author\\\/carmen-de-la-vega\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/author\\\/carmen-de-la-vega\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Como-pasar-la-prueba-oral-DELE.png\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#mainImage\",\"width\":442,\"height\":250,\"caption\":\"C\\u00f3mo pasar la prueba oral del DELE\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/como-pasar-la-prueba-oral-dele\\\/#mainImage\"},\"datePublished\":\"2022-11-22T17:59:56+01:00\",\"dateModified\":\"2022-11-23T11:48:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/\",\"name\":\"Online Spanish school for foreigners\",\"description\":\"Learn Spanish at home\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online","description":"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE","canonical_url":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#article","name":"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online","headline":"C\u00f3mo pasar  la prueba oral DELE","author":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/author\/carmen-de-la-vega\/#author"},"publisher":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Como-pasar-la-prueba-oral-DELE.png","width":442,"height":250,"caption":"C\u00f3mo pasar la prueba oral del DELE"},"datePublished":"2022-11-22T17:59:56+01:00","dateModified":"2022-11-23T11:48:10+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#webpage"},"isPartOf":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#webpage"},"articleSection":"DELE, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/carmeleespanolonline.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/category\/dele-y-siele\/#listItem","name":"DELE"}},{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/category\/dele-y-siele\/#listItem","position":2,"name":"DELE","item":"https:\/\/carmeleespanolonline.com\/blog\/category\/dele-y-siele\/","nextItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#listItem","name":"C\u00f3mo pasar  la prueba oral DELE"},"previousItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#listItem","position":3,"name":"C\u00f3mo pasar  la prueba oral DELE","previousItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/category\/dele-y-siele\/#listItem","name":"DELE"}}]},{"@type":"Organization","@id":"https:\/\/carmeleespanolonline.com\/blog\/#organization","name":"Carmele Espa\u00f1ol Online","description":"Learn Spanish at home","url":"https:\/\/carmeleespanolonline.com\/blog\/","logo":{"@type":"ImageObject","url":"https:\/\/www.carmeleespanolonline.com\/blog\/wp-content\/uploads\/2018\/11\/cropped-Dise\u00f1o-sin-t\u00edtulo.jpg","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#organizationLogo"},"image":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/carmeleespanolonline.com\/blog\/author\/carmen-de-la-vega\/#author","url":"https:\/\/carmeleespanolonline.com\/blog\/author\/carmen-de-la-vega\/","name":"Carmen de la Vega","image":{"@type":"ImageObject","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6834562093b67f5a64864fb30d6e6039390c3840f330a8e4d3ca9eb33d79152c?s=96&r=g","width":96,"height":96,"caption":"Carmen de la Vega"}},{"@type":"WebPage","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#webpage","url":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/","name":"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online","description":"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#breadcrumblist"},"author":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/author\/carmen-de-la-vega\/#author"},"creator":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/author\/carmen-de-la-vega\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2022\/11\/Como-pasar-la-prueba-oral-DELE.png","@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#mainImage","width":442,"height":250,"caption":"C\u00f3mo pasar la prueba oral del DELE"},"primaryImageOfPage":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/#mainImage"},"datePublished":"2022-11-22T17:59:56+01:00","dateModified":"2022-11-23T11:48:10+01:00"},{"@type":"WebSite","@id":"https:\/\/carmeleespanolonline.com\/blog\/#website","url":"https:\/\/carmeleespanolonline.com\/blog\/","name":"Online Spanish school for foreigners","description":"Learn Spanish at home","inLanguage":"es-ES","publisher":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Online Spanish school for foreigners | Learn Spanish at home","og:type":"article","og:title":"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online","og:description":"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE","og:url":"https:\/\/carmeleespanolonline.com\/blog\/como-pasar-la-prueba-oral-dele\/","og:image":"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png","og:image:secure_url":"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png","article:published_time":"2022-11-22T16:59:56+00:00","article:modified_time":"2022-11-23T10:48:10+00:00","twitter:card":"summary","twitter:title":"C\u00f3mo pasar la prueba oral DELE | CarmEle Espa\u00f1ol Online","twitter:description":"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE","twitter:image":"https:\/\/carmeleespanolonline.com\/blog\/wp-content\/uploads\/2023\/12\/image.png"},"aioseo_meta_data":{"post_id":"8624","title":"#post_title | CarmEle Espa\u00f1ol Online","description":"Conoce en qu\u00e9 nos fijamos los examinadores para evaluar tu prueba oral de los ex\u00e1menes del Instituto Cervantes de espa\u00f1ol. \u00a1Consigue tu APTO en el DELE","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-11-07 12:23:36","updated":"2025-06-04 23:57:04"},"_links":{"self":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/posts\/8624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/comments?post=8624"}],"version-history":[{"count":26,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/posts\/8624\/revisions"}],"predecessor-version":[{"id":8825,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/posts\/8624\/revisions\/8825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/media\/8824"}],"wp:attachment":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/media?parent=8624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories?post=8624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/tags?post=8624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}