{"id":39,"count":5,"description":"Conoce de una forma divertida temas relacionados con la cultura espa\u00f1ola y el aprendizaje del idioma","link":"https:\/\/carmeleespanolonline.com\/blog\/category\/directos-en-facebook\/","name":"Directos en Facebook","slug":"directos-en-facebook","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmeleespanolonline.com\/blog\/category\/directos-en-facebook\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/directos-en-facebook\\\/#listItem\",\"name\":\"Directos en Facebook\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/category\\\/directos-en-facebook\\\/#listItem\",\"position\":2,\"name\":\"Directos en Facebook\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/#collectionpage\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/\",\"name\":\"Directos en Facebook | Online Spanish school for foreigners\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#organization\",\"name\":\"Carmele Espa\\u00f1ol Online\",\"description\":\"Learn Spanish at home\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.carmeleespanolonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/cropped-Dise\\u00f1o-sin-t\\u00edtulo.jpg\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/39\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/\",\"name\":\"Online Spanish school for foreigners\",\"description\":\"Learn Spanish at home\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmeleespanolonline.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Directos en Facebook | Online Spanish school for foreigners","description":"","canonical_url":"https:\/\/carmeleespanolonline.com\/blog\/category\/directos-en-facebook\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/carmeleespanolonline.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/category\/directos-en-facebook\/#listItem","name":"Directos en Facebook"}},{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog\/category\/directos-en-facebook\/#listItem","position":2,"name":"Directos en Facebook","previousItem":{"@type":"ListItem","@id":"https:\/\/carmeleespanolonline.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/#collectionpage","url":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/","name":"Directos en Facebook | Online Spanish school for foreigners","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/carmeleespanolonline.com\/blog\/#organization","name":"Carmele Espa\u00f1ol Online","description":"Learn Spanish at home","url":"https:\/\/carmeleespanolonline.com\/blog\/","logo":{"@type":"ImageObject","url":"https:\/\/www.carmeleespanolonline.com\/blog\/wp-content\/uploads\/2018\/11\/cropped-Dise\u00f1o-sin-t\u00edtulo.jpg","@id":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/#organizationLogo"},"image":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/carmeleespanolonline.com\/blog\/#website","url":"https:\/\/carmeleespanolonline.com\/blog\/","name":"Online Spanish school for foreigners","description":"Learn Spanish at home","inLanguage":"es-ES","publisher":{"@id":"https:\/\/carmeleespanolonline.com\/blog\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/carmeleespanolonline.com\/blog\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}